{"id":2083,"date":"2018-12-08T17:48:02","date_gmt":"2018-12-08T22:48:02","guid":{"rendered":"http:\/\/www.jeanmarcpelletier.net\/blog\/?p=2083"},"modified":"2018-12-11T22:39:54","modified_gmt":"2018-12-12T03:39:54","slug":"bombardier-le-pdg-alain-bellemare-se-dit-confiant-et-si-bombardier-de-financait-plutot-via-le-secteur-boursier","status":"publish","type":"post","link":"http:\/\/www.jeanmarcpelletier.net\/blog\/2018\/12\/08\/bombardier-le-pdg-alain-bellemare-se-dit-confiant-et-si-bombardier-de-financait-plutot-via-le-secteur-boursier\/","title":{"rendered":"Bombardier: le PDG Alain Bellemare se dit \u00ab\u00a0confiant\u00a0\u00bb&#8230; &#8211; Et si Bombardier se finan\u00e7ait plut\u00f4t via le secteur boursier?"},"content":{"rendered":"<p>Ainsi, ce jeudi, le PDG Alain Bellemare tenait la rencontre annuelle avec les investisseurs, dans un chic h\u00f4tel de New York, afin de les rassurer sur l&rsquo;avenir de l&rsquo;entreprise et, surtout, les convaincre que son plan de redressement donnerait \u00e0 terme les r\u00e9sultats escompt\u00e9s. Il importe de mentionner le fait que, r\u00e9cemment,<\/p>\n<ol>\n<li>la division a\u00e9ronautique a annonc\u00e9 le licenciement de 5 000 employ\u00e9s, notamment 2 500 emplois qui seront supprim\u00e9s au Qu\u00e9bec d\u00e8s 2019<\/li>\n<li>la division a\u00e9ronautique a c\u00e9d\u00e9 sa division des simulateurs \u00e0 CAE Electronics de Montr\u00e9al<\/li>\n<li>la division a\u00e9ronautique s&rsquo;est d\u00e9partie de sa division DASH (avions s\u00e9rie Q400) avant d&rsquo;en avoir transf\u00e9r\u00e9 la production en Chine<\/li>\n<li>la division a\u00e9ronautique s&rsquo;est d\u00e9partie de sa division des avions citernes CL215, CL315,&#8230; \u00e0 une firme de l&rsquo;Ouest canadien<\/li>\n<li>Bombardier a c\u00e9d\u00e9 les terrains qu&rsquo;elle d\u00e9tenait \u00e0 Downsview (banlieue de Toronto) o\u00f9 les avions de la s\u00e9rie DASH \u00e9taient assembl\u00e9s<\/li>\n<\/ol>\n<p>Au surplus, Bombardier s&rsquo;appr\u00eate \u00e0 mettre en vente les terrains qu&rsquo;elle d\u00e9tient aux abords de l&rsquo;a\u00e9roport Dorval, sans doute afin d&rsquo;augmenter ses liquidit\u00e9s et pr\u00e9senter un meilleur flux de tr\u00e9sorerie (\u00ab\u00a0cash flow\u00a0\u00bb) aux investisseurs.<\/p>\n<p>Et convaincre les futurs acheteurs de ses avions r\u00e9gionaux CRJ et Global qu&rsquo;elle en poursuivra le d\u00e9veloppement et la commercialisation dans l&rsquo;avenir&#8230; ce dont plusieurs doutent, \u00e0 bon escient.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2077 aligncenter\" src=\"http:\/\/www.jeanmarcpelletier.net\/blog\/wp-content\/uploads\/2018\/12\/Le-PDG-de-Bommbardier-est-confiant.png\" alt=\"\" width=\"862\" height=\"480\" srcset=\"http:\/\/www.jeanmarcpelletier.net\/blog\/wp-content\/uploads\/2018\/12\/Le-PDG-de-Bommbardier-est-confiant.png 862w, http:\/\/www.jeanmarcpelletier.net\/blog\/wp-content\/uploads\/2018\/12\/Le-PDG-de-Bommbardier-est-confiant-300x167.png 300w, http:\/\/www.jeanmarcpelletier.net\/blog\/wp-content\/uploads\/2018\/12\/Le-PDG-de-Bommbardier-est-confiant-768x428.png 768w\" sizes=\"auto, (max-width: 862px) 100vw, 862px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Des propos peu rassurants puisque le cours de l&rsquo;action s&rsquo;est maintenu le lendemain de la rencontre avec les investisseurs:<\/p>\n<p style=\"padding-left: 90px;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2085\" src=\"http:\/\/www.jeanmarcpelletier.net\/blog\/wp-content\/uploads\/2018\/12\/Bombardier-Stock.png\" alt=\"\" width=\"711\" height=\"234\" srcset=\"http:\/\/www.jeanmarcpelletier.net\/blog\/wp-content\/uploads\/2018\/12\/Bombardier-Stock.png 617w, http:\/\/www.jeanmarcpelletier.net\/blog\/wp-content\/uploads\/2018\/12\/Bombardier-Stock-300x99.png 300w\" sizes=\"auto, (max-width: 711px) 100vw, 711px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h4>Alain Bellemare demande l&rsquo;aide des gouvernements<\/h4>\n<p>S&rsquo;agissant de la division ferroviaire de Bombardier, laquelle a \u00e9t\u00e9 r\u00e9cemment exclue de la fourniture des trains\/wagons<\/p>\n<ol>\n<li>octroy\u00e9e par Via Rail pour les trains intercit\u00e9s<\/li>\n<li>octroy\u00e9e par la Caisse de d\u00e9p\u00f4t CDPQ pour le mat\u00e9riel ferroviaire du projet REM de Montr\u00e9al<\/li>\n<li>pour le m\u00e9tro de New York \u00e0 cause des retards de livraison pour les tramways de Toronto<\/li>\n<li>pour les m\u00e9tro de Boston et Chicago, la firme chinoise CRRC ayant pr\u00e9sent\u00e9e une soumission 40% inf\u00e9rieure<\/li>\n<\/ol>\n<p>Alain Bellemare interpelle les gouvernements afin que ceux-ci mettent en application une clause \u00ab\u00a0garantissant un contenu local\u00a0\u00bb pour une entreprise tel Bombardier, comme le prescrivent divers gouvernements, ce qui conviendrait aux ententes liant le Canada avec l&rsquo;Organisation mondiale du commerce (OMC) et aux ententes de libre-\u00e9change conclues avec divers partenaires \u00e9trangers.<\/p>\n<p>Cela \u00e9tant, plut\u00f4t que de s&#8217;employer \u00e0 am\u00e9liorer la performance et corriger les d\u00e9ficiences de cette division et faire en sorte qu&rsquo;elle honore \u00ab\u00a0convenablement\u00a0\u00bb les contrats conclus \u00e0 ce jour, le PDG en appelle \u00e0 l&rsquo;aide gouvernementale afin de se faire octroyer des \u00ab\u00a0avantages\u00a0\u00bb pour la fourniture du mat\u00e9riel ferroviaire destin\u00e9 au Canada, tel que relat\u00e9 dans une chronique publi\u00e9e par le Journal de Montr\u00e9al:<\/p>\n<p><a href=\"http:\/\/www.jeanmarcpelletier.net\/blog\/wp-content\/uploads\/2018\/12\/Alain-Bellemare-interpelle-les-gouvernements-Journal-de-Montreal-2018-12-08.pdf\">Alain Bellemare interpelle les gouvernements &#8211; Journal de Montreal &#8211; 2018-12-08<\/a><\/p>\n<p>Au surplus, s&rsquo;agissant de sa division a\u00e9ronautique, des d\u00e9marches ont \u00e9t\u00e9 entreprises afin que le gouvernement du Qu\u00e9bec souscrive, <span style=\"text-decoration: underline;\">\u00e0 nouveau<\/span>, au financement de ses activit\u00e9s au pr\u00e9texte de \u00ab\u00a0pr\u00e9server les emplois locaux\u00a0\u00bb.<\/p>\n<p>Ce que d&rsquo;aucun qualifient de \u00ab\u00a0chantage\u00a0\u00bb \u00e0 l&rsquo;image de celui exerc\u00e9 lors de la quasi-faillite de sa gamme d&rsquo;avions S\u00e9rie C, c\u00e9d\u00e9e par la suite \u00e0 Airbus apr\u00e8s que 1,3 G$ de fonds publics y aient \u00e9t\u00e9 inject\u00e9s&#8230; Le tout, au b\u00e9n\u00e9fice des actionnaires de Bombardier et, principalement, de la famille Bombardier-Beaudoin qui exerce un contr\u00f4le majoritaire sur l&rsquo;entreprise.<\/p>\n<p>&nbsp;<\/p>\n<h4>Le contr\u00f4le absolu exerc\u00e9 par la famille Bombardier-Beaudoin sur l&rsquo;entreprise<\/h4>\n<p>D\u00e8s l&rsquo;entr\u00e9e de Bombardier sur le march\u00e9 boursier afin d&rsquo;assurer le financement de ses activit\u00e9s, l&rsquo;entreprise a structur\u00e9 son capital action de fa\u00e7on telle que les membres de la famille Bombardier-Beaudoin, tout en d\u00e9tenant un nombre d&rsquo;actions minoritaires sur l&rsquo;ensemble des actions, exercaient un contr\u00f4le majoritaire sur l&rsquo;entreprise via des actions (cat\u00e9gorie A) \u00e0 droits de votes multiples. Ainsi, chacune de ces actions dispose d&rsquo;un droit de vote 10 fois sup\u00e9rieur aux actions de cat\u00e9gorie B, ce qui conf\u00e8re \u00e9norm\u00e9ment \u00ab\u00a0de poids\u00a0\u00bb \u00e0 ces actions par rapport \u00e0 celles \u00e9mises sur le march\u00e9 boursier.<\/p>\n<p>Il appert que, destin\u00e9e \u00e0 l&rsquo;origine afin d&rsquo;\u00e9viter une prise de contr\u00f4le hostile par des investisseurs externes, cette structure a \u00e9t\u00e9 &#8211; est &#8211; \u00e0 l&rsquo;origine des nombreuses erreurs strat\u00e9giques commises \u00e0 ce jour, notamment le lancement de la S\u00e9rie C qui allait s&rsquo;av\u00e9rer un gouffre financier majeur, amener l&rsquo;entreprise dans une situation de quasi-faillite et l&rsquo;obliger \u00e0 d\u00e9laisser ses investissements dans les autres produits de la division a\u00e9ronautique ainsi que dans la division ferroviaire.<\/p>\n<p>C&rsquo;est ainsi que, d\u00e9tenant un contr\u00f4le majoritaire sur l&rsquo;entreprise, non seulement les dirigeants \u00e9taient d\u00e9sign\u00e9s \u00e0 m\u00eame les membres de la famille du fondateur de l&rsquo;entreprise mais ils exercent \u00e9galement un contr\u00f4le absolu sur les administrateurs (i.e. les membres du Conseil d&rsquo;administration), dans la mesure o\u00f9 leur vote majoritaire \u00e0 l&rsquo;assembl\u00e9e des actionnaires permet la s\u00e9lection des membres du Conseil d&rsquo;administration r\u00e9pondant aux \u00ab\u00a0attentes sp\u00e9cifiques \u00a0\u00bb de la famille Bombardier-Beaudoin.<\/p>\n<p>Tel que le r\u00e9v\u00e8le une chronique du magazine l&rsquo;Actualit\u00e9, la famille Bombardier-Beaudoin y d\u00e9l\u00e8gue 4 administrateurs apparent\u00e9s \u00e0 la famille du fondateur, en plus d&rsquo;exercer un contr\u00f4le sur la nomination des autres membres du Conseil d&rsquo;adminsitration, faisant en sorte que les dol\u00e9ances et les attentes des actionnaires \u00ab\u00a0inscrits en bourse\u00a0\u00bb passent au second rang:<\/p>\n<p><a href=\"http:\/\/www.jeanmarcpelletier.net\/blog\/wp-content\/uploads\/2018\/12\/Bombardier-Une-affaire-de-famille-L\u2019actualite-2016-03-07.pdf\">Bombardier &#8211; Une affaire de famille &#8211; L\u2019actualite &#8211; 2016-03-07<\/a><\/p>\n<p>Qui plus est, \u00e0 la suite des d\u00e9boires de la S\u00e9rie C dont le projet \u00e9tait g\u00e9r\u00e9 par Pierre Beaudoin &#8211; PDG de Bombardier, fils de Laurent Beaudoin conjoint de Claire Bombardier (fille du fondateur) -, des actionnaires \u00ab\u00a0d&rsquo;importance\u00a0\u00bb ont d\u00fb mener des actions \u00ab\u00a0vigoureuses\u00a0\u00bb afin de l&rsquo;\u00e9vincer de la direction et y nommer Alain Bellemare, dans une \u00ab\u00a0saga\u00a0\u00bb relay\u00e9e dans le Globe and Mail:<\/p>\n<p><a href=\"http:\/\/www.jeanmarcpelletier.net\/blog\/wp-content\/uploads\/2018\/12\/Is-the-worst-over-for-Bommbardier-Globe-and-Mail-2018-04-25.pdf\">Is the worst over for Bommbardier &#8211; Globe and Mail &#8211; 2018-04-25<\/a><\/p>\n<p>C&rsquo;est ainsi que, aujourd&rsquo;hui, malgr\u00e9 la nomination d&rsquo;Alain Bellemmare \u00e0 titre de PDG de l&rsquo;entreprise, les membres de la famille Bombardier-Beaudoin, ne d\u00e9tenant que 13% des actions de l&rsquo;entreprise, exercent un contr\u00f4le \u00e0 hauteur de 59,9% sur les d\u00e9cisions de celle-ci:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2091 aligncenter\" src=\"http:\/\/www.jeanmarcpelletier.net\/blog\/wp-content\/uploads\/2018\/12\/Tableau.png\" alt=\"\" width=\"785\" height=\"593\" srcset=\"http:\/\/www.jeanmarcpelletier.net\/blog\/wp-content\/uploads\/2018\/12\/Tableau.png 785w, http:\/\/www.jeanmarcpelletier.net\/blog\/wp-content\/uploads\/2018\/12\/Tableau-300x227.png 300w, http:\/\/www.jeanmarcpelletier.net\/blog\/wp-content\/uploads\/2018\/12\/Tableau-768x580.png 768w\" sizes=\"auto, (max-width: 785px) 100vw, 785px\" \/><\/p>\n<p>Ainsi, le lien \u00ab\u00a0incestueux\u00a0\u00bb existant entre les membres de la famille Bombardier-Beaudoin et la gestion de l&rsquo;entreprise s&rsquo;av\u00e8re une cause d\u00e9terminante dans les d\u00e9boires v\u00e9cus \u00e0 ce jour alors que les fonds publics qui y sont investis le sont au b\u00e9n\u00e9fice des \u00ab\u00a0int\u00e9r\u00eats premiers\u00a0\u00bb de celle-ci.<\/p>\n<p>&nbsp;<\/p>\n<h4>Les fonds publics investis \u00e0 l&rsquo;avenir dans la S\u00e9rie C&#8230; au b\u00e9n\u00e9fice d&rsquo;Airbus<\/h4>\n<p>Il importe de rappeler \u00e0 notre attention le fait que, en 2016, le gouvernement du Qu\u00e9bec a investi 1,3 G$ dans la filiale de la S\u00e9rie C, une filiale mise sur pied afin d&rsquo;\u00e9viter que le \u00ab\u00a0holding\u00a0\u00bb Bombardier ne soit l&rsquo;objet d&rsquo;une mise en faillite si cette s\u00e9rie continuait \u00e0 encourir les pertes \u00ab\u00a0\u00e0 r\u00e9p\u00e9tition\u00a0\u00bb depuis son lancement.<\/p>\n<p>Ainsi, alors que d&rsquo;aucun estimaient que les fonds publics avaient \u00e9t\u00e9 enti\u00e8rement investis avant sa r\u00e9trocession \u00e0 Airbus, il appert que les apports gouvernementaux non vers\u00e9s \u00e0 ce jour serviront \u00e0 financer l&rsquo;agrandissement des installations de Mirabel, tel que rapport\u00e9 dans une chronique du Journal de Montr\u00e9al:<\/p>\n<p><a href=\"http:\/\/www.jeanmarcpelletier.net\/blog\/wp-content\/uploads\/2018\/12\/Airbus-investit-a-Mirabel-avec-l\u2019argent-de-Bombardier-Journal-de-Montreal-2018-12-04.pdf\">Airbus investit a Mirabel avec l\u2019argent de Bombardier &#8211; Journal de Montreal &#8211; 2018-12-04<\/a><\/p>\n<p>Ainsi, non seulement la s\u00e9rie C a-t-elle \u00e9t\u00e9 c\u00e9d\u00e9e pour 1 $ mais, qui plus est, des fonds publics destin\u00e9s \u00e0 l&rsquo;\u00e9poque afin d&rsquo;\u00e9viter la faillite de Bombardier serviront \u00e0 financer l&rsquo;am\u00e9nagement des hangards de production&#8230; au grand b\u00e9n\u00e9fice d&rsquo;Airbus qui d\u00e9tient une participation majoritaire dans cette filiale&#8230;<\/p>\n<p>&nbsp;<\/p>\n<h4>Que r\u00e9pondre \u00e0 la sollicitation de nouveaux fonds publics men\u00e9e par Bombardier au motif de pr\u00e9server des emplois au Qu\u00e9bec?<\/h4>\n<p>Il est de connaissance publique que la direction de Bombardier a entam\u00e9 des discussions avec le gouvernement du Qu\u00e9bec afin que des fonds publics soient, <span style=\"text-decoration: underline;\">\u00e0 nouveau<\/span>, consentis pour \u00ab\u00a0maintenir \u00e0 flot\u00a0\u00bb la division a\u00e9ronautique, notamment. Et que le ministre Pierre Fitzgibbon appuierait une telle demande au motif de pr\u00e9server des emplois&#8230; et, dans une moindre mesure, de bonifier ses \u00ab\u00a0int\u00e9r\u00eats propres\u00a0\u00bb dans une entreprise fournisseur de produits et services pour Bombardier&#8230;<\/p>\n<p>Or, une opinion \u00e9mise par la chroniqueuse Aur\u00e9lie Lanct\u00f4t du journal Le Devoir questionne vertement l&rsquo;octroi de nouveaux fonds publics au motif que 1) les fonds investis serviraient \u00e0 p\u00e9renniser la mainmise de la famille Bombardier-Beaudoin sur l&rsquo;entreprise, 2) dans la mesure o\u00f9 les entreprises transnationales n&rsquo;ont gu\u00e8re d&rsquo;\u00e9gards pour le maintien des emplois support\u00e9s par des fonds publics et 3) dans la mesure o\u00f9 les gouvernements se font les \u00ab\u00a0messagers\u00a0\u00bb des int\u00e9r\u00eats des grandes entreprises:<\/p>\n<p><a href=\"http:\/\/www.jeanmarcpelletier.net\/blog\/wp-content\/uploads\/2018\/12\/\u00abQu\u2019est-ce-que-tu-veux-qu\u2019on-fasse\u00bb-Le-Devoir-2018-12-08.pdf\">\u00abQu\u2019est-ce que tu veux qu\u2019on fasse\u00bb &#8211; Le Devoir &#8211; 2018-12-08<\/a><\/p>\n<h4><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2098 aligncenter\" src=\"http:\/\/www.jeanmarcpelletier.net\/blog\/wp-content\/uploads\/2018\/12\/Citation-Lanctot.png\" alt=\"\" width=\"1012\" height=\"199\" srcset=\"http:\/\/www.jeanmarcpelletier.net\/blog\/wp-content\/uploads\/2018\/12\/Citation-Lanctot.png 1139w, http:\/\/www.jeanmarcpelletier.net\/blog\/wp-content\/uploads\/2018\/12\/Citation-Lanctot-300x59.png 300w, http:\/\/www.jeanmarcpelletier.net\/blog\/wp-content\/uploads\/2018\/12\/Citation-Lanctot-768x151.png 768w, http:\/\/www.jeanmarcpelletier.net\/blog\/wp-content\/uploads\/2018\/12\/Citation-Lanctot-1024x201.png 1024w\" sizes=\"auto, (max-width: 1012px) 100vw, 1012px\" \/><\/h4>\n<p>&nbsp;<\/p>\n<h4>Et si Bombardier se finan\u00e7ait plut\u00f4t \u00e0 m\u00eame le secteur boursier?<\/h4>\n<p>Il est de coutume, notammment pour les entreprises exer\u00e7ant leurs op\u00e9rations aux Etats-Unis ou en Europe, d&rsquo;assurer leur financement via le secteur boursier ce qui procure les fonds n\u00e9cessaires pour assurer leur d\u00e9veloppement et s&rsquo;av\u00e8re, au surplus, un \u00ab\u00a0test de cr\u00e9dibilit\u00e9\u00a0\u00bb sur la croissance et la valeur future de l&rsquo;entreprise, telle que per\u00e7ue par les investisseurs sollicit\u00e9s \u00e0 cette fin. Alors que, \u00e0 contrario, s&rsquo;appuyer constamment sur des fonds publics pour maintenir une entreprise en op\u00e9ration n&rsquo;est aucunement un gage des succ\u00e8s futurs, de la cr\u00e9dibilit\u00e9 du plan d&rsquo;affaire et de celle des dirigeants assurant la gestion de l&rsquo;entreprise.<\/p>\n<p>Or, l&rsquo;hypoth\u00e8se d&rsquo;une nouvelle \u00e9mission d&rsquo;actions de Bombardier sur le march\u00e9 boursier n&rsquo;a aucunement \u00e9t\u00e9 \u00e9voqu\u00e9e et il appert que, par l&rsquo;\u00e9mission d&rsquo;actions \u00ab\u00a0\u00e0 une juste prix\u00a0\u00bb et, au demeurant, assorties d&rsquo;une option d&rsquo;achat \u00e0 prix futur escompt\u00e9 (\u00ab\u00a0warrant\u00a0\u00bb), Bombardier serait en mesure de souscrire le financement requis afin d&rsquo;assurer la remise sur pied de sa division ferroviaire et garantir aux futurs acheteurs la p\u00e9rennit\u00e9 de sa gamme d&rsquo;avions CRJ et Global. A titre d&rsquo;exemple, l&rsquo;\u00e9mission de 500 M d&rsquo;actions \u00e0 la valeur actuelle transig\u00e9e en bourse procurerait des fonds \u00e0 hauteur de 1 G$ \u00e0 Bombardier, rien de moins.<\/p>\n<p>A l&rsquo;\u00e9vidence, souscrire un financement additionnel via le march\u00e9 boursier pourrait \u00e9liminer le contr\u00f4le absolu d\u00e9tenu par la famille Bombardier-Beaudoin malgr\u00e9 le fait qu&rsquo;elle disposerait, n\u00e9anmoins, d&rsquo;une \u00ab\u00a0minorit\u00e9 de blocage\u00a0\u00bb \u00e9vitant une prise de contr\u00f4le hostile par des investisseurs externes. Cela \u00e9tant, malgr\u00e9 cette option \u00e0 sa disposition, il y a fort \u00e0 parier qu&rsquo;elle s&rsquo;opposerait \u00e0 l&rsquo;apport de fonds via le march\u00e9 boursier &#8211; afin de maintenir un contr\u00f4le absolu sur l&rsquo;entreprise &#8211; et exercera les \u00ab\u00a0pressions requises\u00a0\u00bb afin que les gouvernements consentent, \u00e0 nouveau, des fonds publics \u00e0 l&rsquo;entreprise.<\/p>\n<p>Mais, il n&rsquo;en demeure pas moins que l&rsquo;\u00e9mission de nouvelles actions sur le march\u00e9 boursier, au-del\u00e0 du fait qu&rsquo;elle procurerait des fonds additionnels, serait le test ultime sur la viabilit\u00e9 future de Bombardier, telle que per\u00e7ue par les investisseurs&#8230;<\/p>\n<p style=\"text-align: center;\"><strong>\u00ab\u00a0The Proof is in the Pudding\u00a0\u00bb<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ainsi, ce jeudi, le PDG Alain Bellemare tenait la rencontre annuelle avec les investisseurs, dans un chic h\u00f4tel de New York, afin de les rassurer sur l&rsquo;avenir de l&rsquo;entreprise et, surtout, les convaincre que son plan de redressement donnerait \u00e0 terme les r\u00e9sultats escompt\u00e9s. Il importe de mentionner le fait que, r\u00e9cemment, la division a\u00e9ronautique&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,4],"tags":[],"class_list":["post-2083","post","type-post","status-publish","format-standard","hentry","category-economie-finance","category-rubriques-generiques"],"_links":{"self":[{"href":"http:\/\/www.jeanmarcpelletier.net\/blog\/wp-json\/wp\/v2\/posts\/2083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.jeanmarcpelletier.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.jeanmarcpelletier.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.jeanmarcpelletier.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.jeanmarcpelletier.net\/blog\/wp-json\/wp\/v2\/comments?post=2083"}],"version-history":[{"count":27,"href":"http:\/\/www.jeanmarcpelletier.net\/blog\/wp-json\/wp\/v2\/posts\/2083\/revisions"}],"predecessor-version":[{"id":2114,"href":"http:\/\/www.jeanmarcpelletier.net\/blog\/wp-json\/wp\/v2\/posts\/2083\/revisions\/2114"}],"wp:attachment":[{"href":"http:\/\/www.jeanmarcpelletier.net\/blog\/wp-json\/wp\/v2\/media?parent=2083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.jeanmarcpelletier.net\/blog\/wp-json\/wp\/v2\/categories?post=2083"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.jeanmarcpelletier.net\/blog\/wp-json\/wp\/v2\/tags?post=2083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}